{"id":57400,"date":"2024-04-26T12:59:49","date_gmt":"2024-04-26T10:59:49","guid":{"rendered":"https:\/\/bibliotekapedagogiczna.pl\/?p=57400"},"modified":"2025-09-10T13:09:29","modified_gmt":"2025-09-10T11:09:29","slug":"final-5-mlodziezowego-przegladu-teatralnego","status":"publish","type":"post","link":"https:\/\/bibliotekapedagogiczna.pl\/ru\/final-5-mlodziezowego-przegladu-teatralnego\/","title":{"rendered":"Fina\u0142 5 M\u0142odzie\u017cowego Przegl\u0105du Teatralnego &#8212; Koncert Laureat\u00f3w"},"content":{"rendered":"\n<p>25 kwietnia 2024 w Resursie Obywatelskiej odby\u0142 si\u0119 Koncert Laureat\u00f3w V M\u0142odzie\u017cowego Przegl\u0105du Teatralnego.<\/p>\n\n\n\n<p>Zapraszamy do obejrzenia fotorelacji z tego&nbsp;<a><\/a>wydarzenia.<\/p>\n\n\n<div  id=\"jtg-57397\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Close&quot;,&quot;NEXT&quot;:&quot;Next&quot;,&quot;PREV&quot;:&quot;Previous&quot;,&quot;Error&quot;:&quot;The requested content cannot be loaded. Please try again later.&quot;,&quot;PLAY_START&quot;:&quot;Start slideshow&quot;,&quot;PLAY_STOP&quot;:&quot;Pause slideshow&quot;,&quot;FULL_SCREEN&quot;:&quot;Full screen&quot;,&quot;THUMBS&quot;:&quot;Thumbnails&quot;,&quot;DOWNLOAD&quot;:&quot;Download&quot;,&quot;SHARE&quot;:&quot;Share&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;You can close this modal content with the ESC key&quot;,&quot;ERROR&quot;:&quot;Something Went Wrong, Please Try Again Later&quot;,&quot;IMAGE_ERROR&quot;:&quot;Image Not Found&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;HTML Element Not Found&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error Loading AJAX : Not Found&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error Loading AJAX : Forbidden&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error Loading Page&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Toggle zoom level&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Toggle thumbnails&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Toggle slideshow&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Toggle full-screen mode&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-57397&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Sprawd\\u017a ten niesamowity obrazek!&quot;,&quot;email_message&quot;:&quot;Oto odno\\u015bnik do obrazku: %%image_link%%, a to odno\\u015bnik do galerii: %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57394\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57394\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Zbiorowe zdj\u0119cie laureat\u00f3w 5 M\u0142odzie\u017cowego Przegl\u0105du Teatralnego\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg\" title=\"final-5-przeglad-teatralny-7\" crop=\"\" width=\"1000\" height=\"667\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg 1000w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-300x200.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-768x512.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-24x16.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-36x24.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-48x32.jpg 48w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57391\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57391\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Zesp\u00f3\u0142 m\u0142odzie\u017cy na scenie podczas spektaklu\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6.jpg\" title=\"final-5-przeglad-teatralny-6\" crop=\"\" width=\"1000\" height=\"667\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6.jpg 1000w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6-300x200.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6-768x512.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6-24x16.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6-36x24.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-6-48x32.jpg 48w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57388\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57388\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Zesp\u00f3\u0142 m\u0142odzie\u017cy na scenie podczas spektaklu\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5.jpg\" title=\"final-5-przeglad-teatralny-5\" crop=\"\" width=\"1000\" height=\"667\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5.jpg 1000w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5-300x200.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5-768x512.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5-24x16.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5-36x24.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-5-48x32.jpg 48w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57385\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57385\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Zesp\u00f3\u0142 m\u0142odzie\u017cy na scenie podczas spektaklu\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4.jpg\" title=\"final-5-przeglad-teatralny-4\" crop=\"\" width=\"1000\" height=\"667\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4.jpg 1000w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4-300x200.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4-768x512.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4-24x16.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4-36x24.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-4-48x32.jpg 48w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57382\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57382\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Jury 5 M\u0142odzie\u017cowego Przegl\u0105du Teatralnego na scenie podczas wr\u0119czania dyplom\u00f3w\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3.jpg\" title=\"final-5-przeglad-teatralny-3\" crop=\"\" width=\"1000\" height=\"813\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3.jpg 1000w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3-300x244.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3-768x624.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3-24x20.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3-36x29.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-3-48x39.jpg 48w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57379\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57379\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Publiczno\u015b\u0107 5 M\u0142odzie\u017cowego Przegl\u0105du Teatralnego\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2.jpg\" title=\"final-5-przeglad-teatralny-2\" crop=\"\" width=\"2048\" height=\"1365\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2.jpg 2048w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-300x200.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-1024x683.jpg 1024w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-768x512.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-1536x1024.jpg 1536w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-1320x880.jpg 1320w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-24x16.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-36x24.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-2-48x32.jpg 48w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"57376\" role=\"button\" tabindex=\"0\" rel=\"jtg-57397\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-57376\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Jury 5 M\u0142odzie\u017cowego Przegl\u0105du Teatralnego podczas wr\u0119czania dyplom\u00f3w.\" data-full=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1.jpg\" title=\"final-5-przeglad-teatralny-1\" crop=\"\" width=\"1000\" height=\"667\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1.jpg\" data-src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1.jpg\" data-caption=\"\" srcset=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1.jpg 1000w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1-300x200.jpg 300w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1-768x512.jpg 768w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1-24x16.jpg 24w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1-36x24.jpg 36w, https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-1-48x32.jpg 48w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"http:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/bibliotekapedagogiczna.pl\/ru\/final-5-mlodziezowego-przegladu-teatralnego\/\",\n\t\t\"url\"     : \"https:\/\/bibliotekapedagogiczna.pl\/ru\/final-5-mlodziezowego-przegladu-teatralnego\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>25 kwietnia 2024 w Resursie Obywatelskiej odby\u0142 si\u0119 Koncert Laureat\u00f3w V M\u0142odzie\u017cowego Przegl\u0105du Teatralnego. Zapraszamy do obejrzenia fotorelacji z tego&nbsp;wydarzenia.<\/p>\n","protected":false},"author":914,"featured_media":57394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_oasis_is_in_workflow":0,"_oasis_original":0,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[787],"tags":[],"class_list":["post-57400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-przeglad-teatralny-2"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",1000,667,false],"thumbnail":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-150x150.jpg",150,150,true],"medium":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-300x200.jpg",300,200,true],"medium_large":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-768x512.jpg",768,512,true],"large":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",1000,667,false],"1536x1536":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",1000,667,false],"2048x2048":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",1000,667,false],"img-1100-450":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",675,450,false],"img-1120-800":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",1000,667,false],"img-870-440":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",660,440,false],"img-850-600":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",850,567,false],"img-480-380":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",480,320,false],"img-300-225":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",300,200,false],"img-540-700":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",540,360,false],"img-75-75":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7.jpg",75,50,false],"menu-24x24":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-24x16.jpg",24,16,true],"menu-36x36":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-36x24.jpg",36,24,true],"menu-48x48":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2024\/04\/final-5-przeglad-teatralny-7-48x32.jpg",48,32,true]},"post_excerpt_stackable_v2":"<p>25 kwietnia 2024 w Resursie Obywatelskiej odby\u0142 si\u0119 Koncert Laureat\u00f3w V M\u0142odzie\u017cowego Przegl\u0105du Teatralnego. Zapraszamy do obejrzenia fotorelacji z tego&nbsp;wydarzenia.<\/p>\n","category_list_v2":"<a href=\"https:\/\/bibliotekapedagogiczna.pl\/kategoria\/konkursy\/przeglad-teatralny-2\/\" rel=\"category tag\">M\u0142odzie\u017cowy Przegl\u0105d Teatralny<\/a>","author_info_v2":{"name":"Andrzej Gawro\u0144ski","url":"https:\/\/bibliotekapedagogiczna.pl\/ru\/author\/agawronski\/"},"comments_num_v2":"0 \u043a\u043e\u043c\u043c\u0435\u043d\u0442\u0430\u0440\u0438\u0435\u0432","_links":{"self":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/posts\/57400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/users\/914"}],"replies":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/comments?post=57400"}],"version-history":[{"count":5,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/posts\/57400\/revisions"}],"predecessor-version":[{"id":102928,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/posts\/57400\/revisions\/102928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/media\/57394"}],"wp:attachment":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/media?parent=57400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/categories?post=57400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/tags?post=57400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}