{"id":73,"count":6,"description":"","link":"https:\/\/bibliotekapedagogiczna.pl\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f\/filie-biblioteki-ru\/","name":"Filie biblioteki","slug":"filie-biblioteki-ru","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/categories\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/posts?categories=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}