{"id":116074,"date":"2026-01-21T13:43:29","date_gmt":"2026-01-21T12:43:29","guid":{"rendered":"https:\/\/bibliotekapedagogiczna.pl\/?post_type=books&#038;p=116074"},"modified":"2026-01-21T13:43:29","modified_gmt":"2026-01-21T12:43:29","slug":"blizej-przedszkola","status":"publish","type":"books","link":"https:\/\/bibliotekapedagogiczna.pl\/ru\/books\/blizej-przedszkola\/","title":{"rendered":"Bli\u017cej Przedszkola"},"author":914,"featured_media":116077,"parent":0,"template":"","meta":{"_acf_changed":false,"_oasis_is_in_workflow":0,"_oasis_original":0,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false},"subjects":[90],"class_list":["post-116074","books","type-books","status-publish","has-post-thumbnail","hentry","subjects-czasopisma-ru"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola.jpg",602,812,false],"thumbnail":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-150x150.jpg",150,150,true],"medium":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-222x300.jpg",222,300,true],"medium_large":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola.jpg",602,812,false],"large":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola.jpg",602,812,false],"1536x1536":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola.jpg",602,812,false],"2048x2048":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola.jpg",602,812,false],"img-1100-450":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-602x450.jpg",602,450,true],"img-1120-800":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-602x800.jpg",602,800,true],"img-870-440":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-602x440.jpg",602,440,true],"img-850-600":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-602x600.jpg",602,600,true],"img-480-380":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-480x380.jpg",480,380,true],"img-300-225":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-300x225.jpg",300,225,true],"img-540-700":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-540x700.jpg",540,700,true],"img-75-75":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-75x75.jpg",75,75,true],"menu-24x24":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-18x24.jpg",18,24,true],"menu-36x36":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-27x36.jpg",27,36,true],"menu-48x48":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2026\/01\/blizej-przedszkola-36x48.jpg",36,48,true]},"post_excerpt_stackable_v2":"","category_list_v2":"","author_info_v2":{"name":"Andrzej Gawro\u0144ski","url":"https:\/\/bibliotekapedagogiczna.pl\/ru\/author\/agawronski\/"},"comments_num_v2":"0 \u043a\u043e\u043c\u043c\u0435\u043d\u0442\u0430\u0440\u0438\u0435\u0432","_links":{"self":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/books\/116074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/books"}],"about":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/types\/books"}],"author":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/users\/914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/media\/116077"}],"wp:attachment":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/media?parent=116074"}],"wp:term":[{"taxonomy":"subjects","embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/ru\/wp-json\/wp\/v2\/subjects?post=116074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}