{"id":35998,"date":"2023-07-25T10:25:00","date_gmt":"2023-07-25T08:25:00","guid":{"rendered":"https:\/\/bibliotekapedagogiczna.pl\/?p=35998"},"modified":"2023-12-14T10:38:09","modified_gmt":"2023-12-14T09:38:09","slug":"rodzinne-spotkania","status":"publish","type":"post","link":"https:\/\/bibliotekapedagogiczna.pl\/en\/rodzinne-spotkania\/","title":{"rendered":"Rodzinne Spotkania"},"content":{"rendered":"\n<p>Nawet nam si\u0119 nie \u015bni\u0142o, \u017ce w naszej Bibliotece powstan\u0105 pi\u0119kne \u0142apacze sn\u00f3w. Dzi\u0119kujemy! Spotkania Rodzinne odbywaj\u0105 si\u0119 w ka\u017cdy poniedzia\u0142ek, w Bibliotece Pedagogicznej przy ulicy Ko\u015bciuszki 5a.<\/p>\n\n\n\n<p>Zapraszamy!<\/p>\n\n\n<div class=\"photo-gallery\">\n    <div class=\"container\">\n        <div class=\"intro\">\n                                <\/div>\n        <div class=\"row photos\">\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363333180_656036003220881_7507230682660117154_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363333180_656036003220881_7507230682660117154_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363344028_656036249887523_6785515909694310490_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363344028_656036249887523_6785515909694310490_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363347042_656036303220851_5168407352308118314_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363347042_656036303220851_5168407352308118314_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363347160_656035849887563_3984786372615231194_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363347160_656035849887563_3984786372615231194_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363358680_656035816554233_5074023442618795031_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363358680_656035816554233_5074023442618795031_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363365228_656036043220877_3195787732721509780_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363365228_656036043220877_3195787732721509780_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg\">\n                    <\/a>\n                <\/div>\n                            <div class=\"col-sm-6 col-md-4 col-lg-3 item\">\n                    <a href=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363393430_656036316554183_3351903566305784083_n.jpg\" data-lightbox=\"photos\">\n                        <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363393430_656036316554183_3351903566305784083_n.jpg\">\n                    <\/a>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nawet nam si\u0119 nie \u015bni\u0142o, \u017ce w naszej Bibliotece powstan\u0105 pi\u0119kne \u0142apacze sn\u00f3w. Dzi\u0119kujemy! Spotkania Rodzinne odbywaj\u0105 si\u0119 w ka\u017cdy [&hellip;]<\/p>\n","protected":false},"author":1075,"featured_media":36073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_oasis_is_in_workflow":0,"_oasis_original":0,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-35998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wspieramy-ukraine"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",800,800,false],"thumbnail":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n-150x150.jpg",150,150,true],"medium":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n-300x300.jpg",300,300,true],"medium_large":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n-768x768.jpg",768,768,true],"large":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",800,800,false],"1536x1536":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",800,800,false],"2048x2048":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",800,800,false],"img-1100-450":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",450,450,false],"img-1120-800":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",800,800,false],"img-870-440":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",440,440,false],"img-850-600":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",600,600,false],"img-480-380":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",380,380,false],"img-300-225":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",225,225,false],"img-540-700":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",540,540,false],"img-75-75":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n.jpg",75,75,false],"menu-24x24":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n-24x24.jpg",24,24,true],"menu-36x36":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n-36x36.jpg",36,36,true],"menu-48x48":["https:\/\/bibliotekapedagogiczna.pl\/wp-content\/uploads\/sites\/10\/2023\/12\/363367546_656036219887526_317573409588307779_n-48x48.jpg",48,48,true]},"post_excerpt_stackable_v2":"<p>Nawet nam si\u0119 nie \u015bni\u0142o, \u017ce w naszej Bibliotece powstan\u0105 pi\u0119kne \u0142apacze sn\u00f3w. Dzi\u0119kujemy! Spotkania Rodzinne odbywaj\u0105 si\u0119 w ka\u017cdy poniedzia\u0142ek, w Bibliotece Pedagogicznej przy ulicy Ko\u015bciuszki 5a. Zapraszamy!<\/p>\n","category_list_v2":"<a href=\"https:\/\/bibliotekapedagogiczna.pl\/uk\/kategoria\/wspieramy-ukraine\/\" rel=\"category tag\">Wspieramy Ukrain\u0119<\/a>","author_info_v2":{"name":"pszczubelek","url":"https:\/\/bibliotekapedagogiczna.pl\/en\/author\/pszczubelek\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/posts\/35998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/users\/1075"}],"replies":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/comments?post=35998"}],"version-history":[{"count":2,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/posts\/35998\/revisions"}],"predecessor-version":[{"id":36100,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/posts\/35998\/revisions\/36100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/media\/36073"}],"wp:attachment":[{"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/media?parent=35998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/categories?post=35998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bibliotekapedagogiczna.pl\/en\/wp-json\/wp\/v2\/tags?post=35998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}